{"id":7606,"count":1,"description":"","link":"https:\/\/www.prakun.com\/wp\/tag\/%e0%b9%84%e0%b8%9f%e0%b9%84%e0%b8%ab%e0%b8%a1%e0%b9%89\/","name":"\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49","slug":"%e0%b9%84%e0%b8%9f%e0%b9%84%e0%b8%ab%e0%b8%a1%e0%b9%89","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.1 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49 Archives - \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prakun.com\/wp\/tag\/\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49 Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prakun.com\/wp\/tag\/\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.prakun.com\\\/wp\\\/tag\\\/%e0%b9%84%e0%b8%9f%e0%b9%84%e0%b8%ab%e0%b8%a1%e0%b9%89\\\/\",\"url\":\"https:\\\/\\\/www.prakun.com\\\/wp\\\/tag\\\/%e0%b9%84%e0%b8%9f%e0%b9%84%e0%b8%ab%e0%b8%a1%e0%b9%89\\\/\",\"name\":\"\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49 Archives - \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.prakun.com\\\/wp\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.prakun.com\\\/wp\\\/tag\\\/%e0%b9%84%e0%b8%9f%e0%b9%84%e0%b8%ab%e0%b8%a1%e0%b9%89\\\/#breadcrumb\"},\"inLanguage\":\"th\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.prakun.com\\\/wp\\\/tag\\\/%e0%b9%84%e0%b8%9f%e0%b9%84%e0%b8%ab%e0%b8%a1%e0%b9%89\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.prakun.com\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.prakun.com\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/www.prakun.com\\\/wp\\\/\",\"name\":\"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e23\u0e27\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\",\"description\":\"\u0e07\u0e48\u0e32\u0e22 \u0e04\u0e23\u0e1a \u0e08\u0e1a\u0e40\u0e25\u0e22\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.prakun.com\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49 Archives - \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prakun.com\/wp\/tag\/\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49 Archives","og_url":"https:\/\/www.prakun.com\/wp\/tag\/\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49\/","og_site_name":"\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.prakun.com\/wp\/tag\/%e0%b9%84%e0%b8%9f%e0%b9%84%e0%b8%ab%e0%b8%a1%e0%b9%89\/","url":"https:\/\/www.prakun.com\/wp\/tag\/%e0%b9%84%e0%b8%9f%e0%b9%84%e0%b8%ab%e0%b8%a1%e0%b9%89\/","name":"\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49 Archives - \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19","isPartOf":{"@id":"https:\/\/www.prakun.com\/wp\/#website"},"breadcrumb":{"@id":"https:\/\/www.prakun.com\/wp\/tag\/%e0%b9%84%e0%b8%9f%e0%b9%84%e0%b8%ab%e0%b8%a1%e0%b9%89\/#breadcrumb"},"inLanguage":"th"},{"@type":"BreadcrumbList","@id":"https:\/\/www.prakun.com\/wp\/tag\/%e0%b9%84%e0%b8%9f%e0%b9%84%e0%b8%ab%e0%b8%a1%e0%b9%89\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prakun.com\/wp\/"},{"@type":"ListItem","position":2,"name":"\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49"}]},{"@type":"WebSite","@id":"https:\/\/www.prakun.com\/wp\/#website","url":"https:\/\/www.prakun.com\/wp\/","name":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e23\u0e27\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","description":"\u0e07\u0e48\u0e32\u0e22 \u0e04\u0e23\u0e1a \u0e08\u0e1a\u0e40\u0e25\u0e22","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prakun.com\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"}]}},"_links":{"self":[{"href":"https:\/\/www.prakun.com\/wp\/wp-json\/wp\/v2\/tags\/7606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prakun.com\/wp\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.prakun.com\/wp\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.prakun.com\/wp\/wp-json\/wp\/v2\/posts?tags=7606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}